{"id":100651,"date":"2026-07-15T08:20:33","date_gmt":"2026-07-15T08:20:33","guid":{"rendered":"https:\/\/incm.pt\/site\/?p=100651"},"modified":"2026-07-15T09:28:30","modified_gmt":"2026-07-15T09:28:30","slug":"candidaturas-abertas-a-2-a-edicao-do-premio-incm-solidaria","status":"publish","type":"post","link":"https:\/\/incm.pt\/site\/candidaturas-abertas-a-2-a-edicao-do-premio-incm-solidaria\/","title":{"rendered":"Candidaturas abertas \u00e0 2.\u00aa edi\u00e7\u00e3o do Pr\u00e9mio INCM +Solid\u00e1ria"},"content":{"rendered":"<p>Est\u00e3o abertas, at\u00e9 31 de agosto, as candidaturas \u00e0 2.\u00aa edi\u00e7\u00e3o do Pr\u00e9mio INCM +Solid\u00e1ria, este ano sob o mote Envolve e Desenvolve. Esta \u00e9 uma iniciativa da Imprensa Nacional-Casa da Moeda (INCM) que visa distinguir projetos inovadores no \u00e2mbito da diversidade, equidade e inclus\u00e3o, promovendo a redu\u00e7\u00e3o das desigualdades, a inclus\u00e3o social e o bem-estar de jovens e seniores.<\/p>\n<p>Podem candidatar-se pessoas coletivas de direito privado sem fins lucrativos que integrem a economia social e assumam a forma jur\u00eddica das entidades previstas no Regulamento.<\/p>\n<p>Nesta edi\u00e7\u00e3o, a INCM atribuir\u00e1 um montante global de 30 000 euros, distribu\u00eddo por dois apoios: 20 000 euros para o 1.\u00ba vencedor e 10 000 euros para o 2.\u00ba vencedor, mediante a celebra\u00e7\u00e3o de um protocolo com as entidades distinguidas.<\/p>\n<p>Na sua 2.\u00aa edi\u00e7\u00e3o, o Pr\u00e9mio INCM +Solid\u00e1ria dirige-se a projetos destinados a jovens (dos 15 aos 24 anos) e\/ou seniores (com 65 ou mais anos), que contribuam para a promo\u00e7\u00e3o da autonomia pessoal, da sa\u00fade mental e do bem-estar, bem como para o relacionamento intergeracional, atrav\u00e9s da cultura, da arte, do desporto e da educa\u00e7\u00e3o. Ser\u00e3o valorizadas solu\u00e7\u00f5es inovadoras, exequ\u00edveis, consistentes e com potencial para gerar impacto social a m\u00e9dio prazo.<\/p>\n<p>Os projetos devem ser submetidos, exclusivamente, por via eletr\u00f3nica, atrav\u00e9s do preenchimento do\u00a0<a href=\"https:\/\/incm.pt\/site\/responsabilidade-social\/premio\/candidatura-premio-de-responsabilidade-social\/\">formul\u00e1rio de candidatura<\/a>\u00a0dispon\u00edvel no site da <a href=\"https:\/\/incm.pt\/site\/index.php\">INCM<\/a>.<\/p>\n<p>De acordo com o\u00a0<a href=\"https:\/\/incm.pt\/site\/wp-content\/uploads\/2026\/07\/Regulamento-INCM_Solidaria-2026.pdf\">regulamento do pr\u00e9mio<\/a>, o\u00a0<a href=\"https:\/\/incm.pt\/site\/juri-do-premio-de-responsabilidade-social\/\">j\u00fari<\/a>, presidido por Concei\u00e7\u00e3o Zagalo, e composto por Cristiana Ferreira e Filipe Almeida, avaliar\u00e1 os projetos submetidos tendo em conta o seu impacto social, a sua relev\u00e2ncia, o seu potencial de crescimento, o detalhe do seu or\u00e7amento, a inova\u00e7\u00e3o da solu\u00e7\u00e3o proposta e a capacidade da entidade concorrente para o implementar.<\/p>\n<p>Com esta iniciativa, a INCM refor\u00e7a o seu compromisso com a responsabilidade social, apoiando projetos que contribuam para uma sociedade mais inclusiva, coesa e preparada para responder aos desafios das diferentes gera\u00e7\u00f5es.<\/p>\n<p>Saiba mais em\u00a0<a href=\"https:\/\/incm.pt\/site\/responsabilidade-social\/premio\/\">Pr\u00e9mio de Responsabilidade Social INCM +Solid\u00e1ria<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Est\u00e3o abertas, at\u00e9 31 de agosto, as candidaturas \u00e0 2.\u00aa edi\u00e7\u00e3o do Pr\u00e9mio INCM +Solid\u00e1ria, este ano sob o mote Envolve e Desenvolve. Esta \u00e9 uma iniciativa da Imprensa Nacional-Casa da Moeda (INCM) que visa distinguir projetos inovadores no \u00e2mbito da diversidade, equidade e inclus\u00e3o, promovendo a redu\u00e7\u00e3o das desigualdades, a inclus\u00e3o social e o [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":100657,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1,191],"tags":[],"class_list":["post-100651","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","category-responsabilidade-social"],"acf":[],"_links":{"self":[{"href":"https:\/\/incm.pt\/site\/wp-json\/wp\/v2\/posts\/100651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/incm.pt\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/incm.pt\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/incm.pt\/site\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/incm.pt\/site\/wp-json\/wp\/v2\/comments?post=100651"}],"version-history":[{"count":1,"href":"https:\/\/incm.pt\/site\/wp-json\/wp\/v2\/posts\/100651\/revisions"}],"predecessor-version":[{"id":100656,"href":"https:\/\/incm.pt\/site\/wp-json\/wp\/v2\/posts\/100651\/revisions\/100656"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/incm.pt\/site\/wp-json\/wp\/v2\/media\/100657"}],"wp:attachment":[{"href":"https:\/\/incm.pt\/site\/wp-json\/wp\/v2\/media?parent=100651"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/incm.pt\/site\/wp-json\/wp\/v2\/categories?post=100651"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/incm.pt\/site\/wp-json\/wp\/v2\/tags?post=100651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}